    <style>
        .overlay {
            position: absolute;
            top: 0;
            left: 0;
            width: 100%;
            height: 100%;
            background-color: rgba(58, 52, 42, 0.7);
            display: flex;
            flex-direction: column;
            align-items: center;
            justify-content: center;
            transition: background-color 0.7s ease;
        }

        .title-box {
            display: flex;
            align-items: center;
            justify-content: center;
            transition: all 0.7s ease;
            padding: 10px;
            border: 2px solid white;
            transform: scale(0);
            position: absolute;
            width: 90%;
            height: 90%;
            top: 50%;
            left: 50%;
            transform: translate(-50%, -50%) scale(0);
        }

        .img-container:hover .overlay {
            background-color: rgba(58, 52, 42, 0.3);
        }

        .img-container:hover .title-box {
            transform: translate(-50%, -50%) scale(1);
        }

        .img-container:hover .title-h3 {
            transform: translateY(-10px);
        }

        .img-container:hover .see-more {
            opacity: 1;
        }

        .title-h3 {
            position: relative;
            color: white;
            margin: 0;
            z-index: 1;
            /* Ensure the title is above the growing border box */
            transition: transform 0.7s ease;
        }

        .see-more {
            position: relative;
            color: white;
            margin-top: 10px;
            opacity: 0;
            transition: opacity 0.7s ease;
            z-index: 1;
            /* Ensure the "See more" text is above the growing border box */
        }

        .img-container {
            position: relative;
            overflow: hidden;
        }

        .tabs {
            margin-bottom: 20px;
            text-align: left;
        }

        .tabs button {
            background-color: #444;
            color: white;
            border: none;
            padding: 10px 20px;
            cursor: pointer;
            transition: background-color 0.3s ease;
        }

        .tabs button:hover,
        .tabs button.active {
            background-color: #666;
        }

        .post-item {
            display: none;
        }
    </style>

<div class="tabs " style="margin-top: 40px">
        <button class="tab-link active" data-category="all">All</button>
        <button class="tab-link" data-category="novinky-2020">News 2020</button>
        <button class="tab-link" data-category="novinky-2019">News 2019</button>
        <button class="tab-link" data-category="novinky-2018">News 2018</button>
        <button class="tab-link" data-category="novinky-2017">News 2017</button>
        <button class="tab-link" data-category="novinky-2016">News 2016</button>
    </div>

    <div class="row justify-content-center">
                    <div class="col-12 col-lg-4 post-item" data-category="news-2020" style="margin-bottom: 25px;">
                <a href="https://www.scmetal.cz/en/renovation/" class="d-block">
                    <div class="img-container">
                        <div>
                            <img style="aspect-ratio: 3/2; width: 100%" height="260" src="https://www.scmetal.cz/wp-content/uploads/2021/01/001.jpg" alt="">
                        </div>
                        <div class="overlay">
                            <h3 class="title-h3 h4 text-center">Renovation</h3>
                            <div style="color: #ff9933;" class="see-more h3">More</div>
                            <div class="title-box"></div>
                        </div>
                    </div>
                </a>
            </div>
                    <div class="col-12 col-lg-4 post-item" data-category="news-2020" style="margin-bottom: 25px;">
                <a href="https://www.scmetal.cz/en/new-water-filtration/" class="d-block">
                    <div class="img-container">
                        <div>
                            <img style="aspect-ratio: 3/2; width: 100%" height="260" src="https://www.scmetal.cz/wp-content/uploads/2020/02/20200121_124035.jpg" alt="">
                        </div>
                        <div class="overlay">
                            <h3 class="title-h3 h4 text-center">New water filtration</h3>
                            <div style="color: #ff9933;" class="see-more h3">More</div>
                            <div class="title-box"></div>
                        </div>
                    </div>
                </a>
            </div>
                    <div class="col-12 col-lg-4 post-item" data-category="news-2020" style="margin-bottom: 25px;">
                <a href="https://www.scmetal.cz/en/fleet-renewal/" class="d-block">
                    <div class="img-container">
                        <div>
                            <img style="aspect-ratio: 3/2; width: 100%" height="260" src="https://www.scmetal.cz/wp-content/uploads/2020/02/image1-scaled.jpg" alt="">
                        </div>
                        <div class="overlay">
                            <h3 class="title-h3 h4 text-center">Vehicle fleet renewal</h3>
                            <div style="color: #ff9933;" class="see-more h3">More</div>
                            <div class="title-box"></div>
                        </div>
                    </div>
                </a>
            </div>
                    <div class="col-12 col-lg-4 post-item" data-category="news-2019" style="margin-bottom: 25px;">
                <a href="https://www.scmetal.cz/en/new-branch-office/" class="d-block">
                    <div class="img-container">
                        <div>
                            <img style="aspect-ratio: 3/2; width: 100%" height="260" src="https://www.scmetal.cz/wp-content/uploads/2020/02/20190827_165601.jpg" alt="">
                        </div>
                        <div class="overlay">
                            <h3 class="title-h3 h4 text-center">New branch office</h3>
                            <div style="color: #ff9933;" class="see-more h3">More</div>
                            <div class="title-box"></div>
                        </div>
                    </div>
                </a>
            </div>
                    <div class="col-12 col-lg-4 post-item" data-category="news-2019" style="margin-bottom: 25px;">
                <a href="https://www.scmetal.cz/en/parking-lot-pavement/" class="d-block">
                    <div class="img-container">
                        <div>
                            <img style="aspect-ratio: 3/2; width: 100%" height="260" src="https://www.scmetal.cz/wp-content/uploads/2019/05/20190527_172523-e1559135478843.jpg" alt="">
                        </div>
                        <div class="overlay">
                            <h3 class="title-h3 h4 text-center">Parking lot pavement</h3>
                            <div style="color: #ff9933;" class="see-more h3">More</div>
                            <div class="title-box"></div>
                        </div>
                    </div>
                </a>
            </div>
                    <div class="col-12 col-lg-4 post-item" data-category="news-2019" style="margin-bottom: 25px;">
                <a href="https://www.scmetal.cz/en/new-press-brake/" class="d-block">
                    <div class="img-container">
                        <div>
                            <img style="aspect-ratio: 3/2; width: 100%" height="260" src="https://www.scmetal.cz/wp-content/uploads/2019/05/OL-nový.png" alt="">
                        </div>
                        <div class="overlay">
                            <h3 class="title-h3 h4 text-center">New press brake</h3>
                            <div style="color: #ff9933;" class="see-more h3">More</div>
                            <div class="title-box"></div>
                        </div>
                    </div>
                </a>
            </div>
                    <div class="col-12 col-lg-4 post-item" data-category="news-2019" style="margin-bottom: 25px;">
                <a href="https://www.scmetal.cz/en/marking-device/" class="d-block">
                    <div class="img-container">
                        <div>
                            <img style="aspect-ratio: 3/2; width: 100%" height="260" src="https://www.scmetal.cz/wp-content/uploads/2019/05/couth-mc2000n-hq.jpg" alt="">
                        </div>
                        <div class="overlay">
                            <h3 class="title-h3 h4 text-center">Marking device</h3>
                            <div style="color: #ff9933;" class="see-more h3">More</div>
                            <div class="title-box"></div>
                        </div>
                    </div>
                </a>
            </div>
                    <div class="col-12 col-lg-4 post-item" data-category="news-2018" style="margin-bottom: 25px;">
                <a href="https://www.scmetal.cz/en/mobile-forklift-wash/" class="d-block">
                    <div class="img-container">
                        <div>
                            <img style="aspect-ratio: 3/2; width: 100%" height="260" src="https://www.scmetal.cz/wp-content/uploads/2018/11/myčka_I.jpg" alt="">
                        </div>
                        <div class="overlay">
                            <h3 class="title-h3 h4 text-center">Mobile forklift wash</h3>
                            <div style="color: #ff9933;" class="see-more h3">More</div>
                            <div class="title-box"></div>
                        </div>
                    </div>
                </a>
            </div>
                    <div class="col-12 col-lg-4 post-item" data-category="news-2018" style="margin-bottom: 25px;">
                <a href="https://www.scmetal.cz/en/pribyslav-malta-primary-school-2018/" class="d-block">
                    <div class="img-container">
                        <div>
                            <img style="aspect-ratio: 3/2; width: 100%" height="260" src="https://www.scmetal.cz/wp-content/uploads/2018/10/03.jpg" alt="">
                        </div>
                        <div class="overlay">
                            <h3 class="title-h3 h4 text-center">Přibyslav Primary School &#8211; Malta 2018</h3>
                            <div style="color: #ff9933;" class="see-more h3">More</div>
                            <div class="title-box"></div>
                        </div>
                    </div>
                </a>
            </div>
                    <div class="col-12 col-lg-4 post-item" data-category="news-2018" style="margin-bottom: 25px;">
                <a href="https://www.scmetal.cz/en/new-8kw-laser/" class="d-block">
                    <div class="img-container">
                        <div>
                            <img style="aspect-ratio: 3/2; width: 100%" height="260" src="https://www.scmetal.cz/wp-content/uploads/2018/09/Fiber-8kW-vcetne-automatizace4.jpg" alt="">
                        </div>
                        <div class="overlay">
                            <h3 class="title-h3 h4 text-center">New 8kW laser</h3>
                            <div style="color: #ff9933;" class="see-more h3">More</div>
                            <div class="title-box"></div>
                        </div>
                    </div>
                </a>
            </div>
                    <div class="col-12 col-lg-4 post-item" data-category="news-2018" style="margin-bottom: 25px;">
                <a href="https://www.scmetal.cz/en/paving-the-warehouse-area/" class="d-block">
                    <div class="img-container">
                        <div>
                            <img style="aspect-ratio: 3/2; width: 100%" height="260" src="https://www.scmetal.cz/wp-content/uploads/2018/09/Vyasfaltování-ploch-za-skladem.jpg" alt="">
                        </div>
                        <div class="overlay">
                            <h3 class="title-h3 h4 text-center">Paving the warehouse area</h3>
                            <div style="color: #ff9933;" class="see-more h3">More</div>
                            <div class="title-box"></div>
                        </div>
                    </div>
                </a>
            </div>
                    <div class="col-12 col-lg-4 post-item" data-category="news-2018" style="margin-bottom: 25px;">
                <a href="https://www.scmetal.cz/en/new-flooring-in-tabor/" class="d-block">
                    <div class="img-container">
                        <div>
                            <img style="aspect-ratio: 3/2; width: 100%" height="260" src="https://www.scmetal.cz/wp-content/uploads/2019/05/OL-nový.png" alt="">
                        </div>
                        <div class="overlay">
                            <h3 class="title-h3 h4 text-center">New flooring in Tábor</h3>
                            <div style="color: #ff9933;" class="see-more h3">More</div>
                            <div class="title-box"></div>
                        </div>
                    </div>
                </a>
            </div>
                    <div class="col-12 col-lg-4 post-item" data-category="news-2018" style="margin-bottom: 25px;">
                <a href="https://www.scmetal.cz/en/they-wrote-about-us/" class="d-block">
                    <div class="img-container">
                        <div>
                            <img style="aspect-ratio: 3/2; width: 100%" height="260" src="https://www.scmetal.cz/wp-content/uploads/2017/07/Ronzani-Marbling-Machine-2000-04-1.jpg" alt="">
                        </div>
                        <div class="overlay">
                            <h3 class="title-h3 h4 text-center">They wrote about us</h3>
                            <div style="color: #ff9933;" class="see-more h3">More</div>
                            <div class="title-box"></div>
                        </div>
                    </div>
                </a>
            </div>
                    <div class="col-12 col-lg-4 post-item" data-category="news-2018" style="margin-bottom: 25px;">
                <a href="https://www.scmetal.cz/en/new-rack-taken/" class="d-block">
                    <div class="img-container">
                        <div>
                            <img style="aspect-ratio: 3/2; width: 100%" height="260" src="https://www.scmetal.cz/wp-content/uploads/2018/09/Nový-regál.jpg" alt="">
                        </div>
                        <div class="overlay">
                            <h3 class="title-h3 h4 text-center">New racking system acquired</h3>
                            <div style="color: #ff9933;" class="see-more h3">More</div>
                            <div class="title-box"></div>
                        </div>
                    </div>
                </a>
            </div>
                    <div class="col-12 col-lg-4 post-item" data-category="news-2018" style="margin-bottom: 25px;">
                <a href="https://www.scmetal.cz/en/iso-90012015-and-140012015/" class="d-block">
                    <div class="img-container">
                        <div>
                            <img style="aspect-ratio: 3/2; width: 100%" height="260" src="https://www.scmetal.cz/wp-content/uploads/2019/12/14001-1-pdf.jpg" alt="">
                        </div>
                        <div class="overlay">
                            <h3 class="title-h3 h4 text-center">ISO 9001:2015 and 14001:2015</h3>
                            <div style="color: #ff9933;" class="see-more h3">More</div>
                            <div class="title-box"></div>
                        </div>
                    </div>
                </a>
            </div>
                    <div class="col-12 col-lg-4 post-item" data-category="news-2017" style="margin-bottom: 25px;">
                <a href="https://www.scmetal.cz/en/built-in-warehouse-office/" class="d-block">
                    <div class="img-container">
                        <div>
                            <img style="aspect-ratio: 3/2; width: 100%" height="260" src="https://www.scmetal.cz/wp-content/uploads/2017/12/Vestavek-V..jpg" alt="">
                        </div>
                        <div class="overlay">
                            <h3 class="title-h3 h4 text-center">Built-in warehouse office</h3>
                            <div style="color: #ff9933;" class="see-more h3">More</div>
                            <div class="title-box"></div>
                        </div>
                    </div>
                </a>
            </div>
                    <div class="col-12 col-lg-4 post-item" data-category="news-2017" style="margin-bottom: 25px;">
                <a href="https://www.scmetal.cz/en/moving-the-slitting-machine/" class="d-block">
                    <div class="img-container">
                        <div>
                            <img style="aspect-ratio: 3/2; width: 100%" height="260" src="https://www.scmetal.cz/wp-content/uploads/2017/07/Jorns-02.png" alt="">
                        </div>
                        <div class="overlay">
                            <h3 class="title-h3 h4 text-center">Moving the slitting machine</h3>
                            <div style="color: #ff9933;" class="see-more h3">More</div>
                            <div class="title-box"></div>
                        </div>
                    </div>
                </a>
            </div>
                    <div class="col-12 col-lg-4 post-item" data-category="news-2017" style="margin-bottom: 25px;">
                <a href="https://www.scmetal.cz/en/acquisition-of-a-new-central-compressor-room/" class="d-block">
                    <div class="img-container">
                        <div>
                            <img style="aspect-ratio: 3/2; width: 100%" height="260" src="https://www.scmetal.cz/wp-content/uploads/2017/09/20170918_091633.jpg" alt="">
                        </div>
                        <div class="overlay">
                            <h3 class="title-h3 h4 text-center">Acquisition of a new central compressor room</h3>
                            <div style="color: #ff9933;" class="see-more h3">More</div>
                            <div class="title-box"></div>
                        </div>
                    </div>
                </a>
            </div>
                    <div class="col-12 col-lg-4 post-item" data-category="news-2017" style="margin-bottom: 25px;">
                <a href="https://www.scmetal.cz/en/installation-of-central-welding-extraction/" class="d-block">
                    <div class="img-container">
                        <div>
                            <img style="aspect-ratio: 3/2; width: 100%" height="260" src="https://www.scmetal.cz/wp-content/uploads/2017/09/centrálmí-odsávání.jpg" alt="">
                        </div>
                        <div class="overlay">
                            <h3 class="title-h3 h4 text-center">Installation of welding fume extraction</h3>
                            <div style="color: #ff9933;" class="see-more h3">More</div>
                            <div class="title-box"></div>
                        </div>
                    </div>
                </a>
            </div>
                    <div class="col-12 col-lg-4 post-item" data-category="news-2017" style="margin-bottom: 25px;">
                <a href="https://www.scmetal.cz/en/purchase-of-a-new-premises/" class="d-block">
                    <div class="img-container">
                        <div>
                            <img style="aspect-ratio: 3/2; width: 100%" height="260" src="https://www.scmetal.cz/wp-content/uploads/2017/09/nový-areál.jpg" alt="">
                        </div>
                        <div class="overlay">
                            <h3 class="title-h3 h4 text-center">Purchase of a new premises</h3>
                            <div style="color: #ff9933;" class="see-more h3">More</div>
                            <div class="title-box"></div>
                        </div>
                    </div>
                </a>
            </div>
                    <div class="col-12 col-lg-4 post-item" data-category="news-2017" style="margin-bottom: 25px;">
                <a href="https://www.scmetal.cz/en/waste-management-and-joinery-space/" class="d-block">
                    <div class="img-container">
                        <div>
                            <img style="aspect-ratio: 3/2; width: 100%" height="260" src="https://www.scmetal.cz/wp-content/uploads/2017/09/20170918_091757.jpg" alt="">
                        </div>
                        <div class="overlay">
                            <h3 class="title-h3 h4 text-center">Waste management and joinery space</h3>
                            <div style="color: #ff9933;" class="see-more h3">More</div>
                            <div class="title-box"></div>
                        </div>
                    </div>
                </a>
            </div>
                    <div class="col-12 col-lg-4 post-item" data-category="news-2017" style="margin-bottom: 25px;">
                <a href="https://www.scmetal.cz/en/new-laser-lvd-phoenix-fl-3015-6kw/" class="d-block">
                    <div class="img-container">
                        <div>
                            <img style="aspect-ratio: 3/2; width: 100%" height="260" src="https://www.scmetal.cz/wp-content/uploads/2017/09/LVD_Phoenix-FL-3015-400x258.jpg" alt="">
                        </div>
                        <div class="overlay">
                            <h3 class="title-h3 h4 text-center">New Laser LVD Phoenix FL-3015 6kW</h3>
                            <div style="color: #ff9933;" class="see-more h3">More</div>
                            <div class="title-box"></div>
                        </div>
                    </div>
                </a>
            </div>
                    <div class="col-12 col-lg-4 post-item" data-category="news-2017" style="margin-bottom: 25px;">
                <a href="https://www.scmetal.cz/en/building-new-grinding-room/" class="d-block">
                    <div class="img-container">
                        <div>
                            <img style="aspect-ratio: 3/2; width: 100%" height="260" src="https://www.scmetal.cz/wp-content/uploads/2017/09/nová-brusírna-II..jpg" alt="">
                        </div>
                        <div class="overlay">
                            <h3 class="title-h3 h4 text-center">Building new grinding room</h3>
                            <div style="color: #ff9933;" class="see-more h3">More</div>
                            <div class="title-box"></div>
                        </div>
                    </div>
                </a>
            </div>
                    <div class="col-12 col-lg-4 post-item" data-category="news-2017" style="margin-bottom: 25px;">
                <a href="https://www.scmetal.cz/en/acquisition-of-pattern-polishing-machine/" class="d-block">
                    <div class="img-container">
                        <div>
                            <img style="aspect-ratio: 3/2; width: 100%" height="260" src="https://www.scmetal.cz/wp-content/uploads/2017/09/Kroužkovací-linka.jpg" alt="">
                        </div>
                        <div class="overlay">
                            <h3 class="title-h3 h4 text-center">Acquisition of pattern-polishing machine</h3>
                            <div style="color: #ff9933;" class="see-more h3">More</div>
                            <div class="title-box"></div>
                        </div>
                    </div>
                </a>
            </div>
                    <div class="col-12 col-lg-4 post-item" data-category="news-2016-en" style="margin-bottom: 25px;">
                <a href="https://www.scmetal.cz/en/installation-of-oil-separators/" class="d-block">
                    <div class="img-container">
                        <div>
                            <img style="aspect-ratio: 3/2; width: 100%" height="260" src="https://www.scmetal.cz/wp-content/uploads/2017/09/Odlučovač-ropných-látek.jpg" alt="">
                        </div>
                        <div class="overlay">
                            <h3 class="title-h3 h4 text-center">Installation of oil separators</h3>
                            <div style="color: #ff9933;" class="see-more h3">More</div>
                            <div class="title-box"></div>
                        </div>
                    </div>
                </a>
            </div>
                    <div class="col-12 col-lg-4 post-item" data-category="news-2016-en" style="margin-bottom: 25px;">
                <a href="https://www.scmetal.cz/en/new-warehouse-opening/" class="d-block">
                    <div class="img-container">
                        <div>
                            <img style="aspect-ratio: 3/2; width: 100%" height="260" src="https://www.scmetal.cz/wp-content/uploads/2017/06/Image38-1-1.jpg" alt="">
                        </div>
                        <div class="overlay">
                            <h3 class="title-h3 h4 text-center">New Warehouse opening</h3>
                            <div style="color: #ff9933;" class="see-more h3">More</div>
                            <div class="title-box"></div>
                        </div>
                    </div>
                </a>
            </div>
            </div>

    <script src="https://code.jquery.com/jquery-3.6.0.min.js"></script>
    <script>
        $(document).ready(function() {
            function filterPosts(category) {
                if (category === 'all') {
                    $('.post-item').show();
                } else {
                    $('.post-item').hide();
                    $('.post-item').each(function() {
                        if ($(this).data('category').split(' ').indexOf(category) !== -1) {
                            $(this).show();
                        }
                    });
                }
            }

            $('.tab-link').click(function() {
                $('.tab-link').removeClass('active');
                $(this).addClass('active');
                var category = $(this).data('category');
                filterPosts(category);
            });

            // Initially show all posts
            filterPosts('all');

            $('.img-container').hover(function() {
                $(this).find('.title-box').css('transform', 'translate(-50%, -50%) scale(1)');
                $(this).find('.title-h3').css('transform', 'translateY(-10px)');
                $(this).find('.see-more').css('opacity', '1');
            }, function() {
                $(this).find('.title-box').css('transform', 'translate(-50%, -50%) scale(0)');
                $(this).find('.title-h3').css('transform', 'translateY(0)');
                $(this).find('.see-more').css('opacity', '0');
            });
        });
    </script>
{"id":9030,"date":"2019-11-28T18:00:23","date_gmt":"2019-11-28T17:00:23","guid":{"rendered":"https:\/\/cz24.info\/news\/"},"modified":"2024-06-21T18:45:45","modified_gmt":"2024-06-21T16:45:45","slug":"news","status":"publish","type":"page","link":"https:\/\/www.scmetal.cz\/en\/news\/","title":{"rendered":"News"},"content":{"rendered":"[vc_row full_width=&#8221;stretch_row_content&#8221; bg_type=&#8221;image&#8221; parallax_style=&#8221;vcpb-default&#8221; bg_image_new=&#8221;id^7494|url^http:\/\/scmetal.cz\/wp-content\/uploads\/sites\/19\/2017\/06\/demo-cb1-1.jpg|caption^null|alt^null|title^demo-cb1|description^null&#8221; bg_image_repeat=&#8221;no-repeat&#8221; bg_img_attach=&#8221;fixed&#8221; bg_override=&#8221;ex-full&#8221; header_style=&#8221;qodef-light-header&#8221; anchor=&#8221;implementace-reference&#8221; el_id=&#8221;implementace-reference&#8221;][vc_column][vc_row_inner][vc_column_inner el_class=&#8221;blok_hlavicka1&#8243;][vc_empty_space height=&#8221;120&#8243;][vc_custom_heading text=&#8221;News&#8221; font_container=&#8221;tag:h1|text_align:center|color:%23ffffff&#8221; use_theme_fonts=&#8221;yes&#8221;][vc_empty_space height=&#8221;25&#8243;][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row][vc_column][vc_empty_space][\/vc_column][\/vc_row][vc_row][vc_column][\/vc_column][\/vc_row]\n","protected":false},"excerpt":{"rendered":"<p>[vc_row full_width=&#8221;stretch_row_content&#8221; bg_type=&#8221;image&#8221; parallax_style=&#8221;vcpb-default&#8221; bg_image_new=&#8221;id^7494|url^http:\/\/scmetal.cz\/wp-content\/uploads\/sites\/19\/2017\/06\/demo-cb1-1.jpg|caption^null|alt^null|title^demo-cb1|description^null&#8221; bg_image_repeat=&#8221;no-repeat&#8221; bg_img_attach=&#8221;fixed&#8221; bg_override=&#8221;ex-full&#8221; header_style=&#8221;qodef-light-header&#8221; anchor=&#8221;implementace-reference&#8221; el_id=&#8221;implementace-reference&#8221;][vc_column][vc_row_inner][vc_column_inner el_class=&#8221;blok_hlavicka1&#8243;][vc_empty_space height=&#8221;120&#8243;][vc_custom_heading text=&#8221;News&#8221; font_container=&#8221;tag:h1|text_align:center|color:%23ffffff&#8221; use_theme_fonts=&#8221;yes&#8221;][vc_empty_space height=&#8221;25&#8243;][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row][vc_column][vc_empty_space][\/vc_column][\/vc_row][vc_row][vc_column][\/vc_column][\/vc_row]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-9030","page","type-page","status-publish","hentry","entry","post-inner"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>News | scmetal.cz<\/title>\n<meta name=\"description\" content=\"News from the life of SC Metal s.r.o. Latest technology, events, production news, metallurgical materials, career.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.scmetal.cz\/en\/news\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"News | scmetal.cz\" \/>\n<meta property=\"og:description\" content=\"News from the life of SC Metal s.r.o. Latest technology, events, production news, metallurgical materials, career.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.scmetal.cz\/en\/news\/\" \/>\n<meta property=\"og:site_name\" content=\"scmetal.cz\" \/>\n<meta property=\"article:modified_time\" content=\"2024-06-21T16:45:45+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.scmetal.cz\\\/en\\\/news\\\/\",\"url\":\"https:\\\/\\\/www.scmetal.cz\\\/en\\\/news\\\/\",\"name\":\"News | scmetal.cz\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.scmetal.cz\\\/#website\"},\"datePublished\":\"2019-11-28T17:00:23+00:00\",\"dateModified\":\"2024-06-21T16:45:45+00:00\",\"description\":\"News from the life of SC Metal s.r.o. Latest technology, events, production news, metallurgical materials, career.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.scmetal.cz\\\/en\\\/news\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.scmetal.cz\\\/en\\\/news\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.scmetal.cz\\\/en\\\/news\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Dom\u016f\",\"item\":\"https:\\\/\\\/www.scmetal.cz\\\/?lang=en\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"News\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.scmetal.cz\\\/#website\",\"url\":\"https:\\\/\\\/www.scmetal.cz\\\/\",\"name\":\"scmetal.cz\",\"description\":\"komplexn\u00ed servis pro stroj\u00edrenstv\u00ed\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.scmetal.cz\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"News | scmetal.cz","description":"News from the life of SC Metal s.r.o. Latest technology, events, production news, metallurgical materials, career.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.scmetal.cz\/en\/news\/","og_locale":"en_US","og_type":"article","og_title":"News | scmetal.cz","og_description":"News from the life of SC Metal s.r.o. Latest technology, events, production news, metallurgical materials, career.","og_url":"https:\/\/www.scmetal.cz\/en\/news\/","og_site_name":"scmetal.cz","article_modified_time":"2024-06-21T16:45:45+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.scmetal.cz\/en\/news\/","url":"https:\/\/www.scmetal.cz\/en\/news\/","name":"News | scmetal.cz","isPartOf":{"@id":"https:\/\/www.scmetal.cz\/#website"},"datePublished":"2019-11-28T17:00:23+00:00","dateModified":"2024-06-21T16:45:45+00:00","description":"News from the life of SC Metal s.r.o. Latest technology, events, production news, metallurgical materials, career.","breadcrumb":{"@id":"https:\/\/www.scmetal.cz\/en\/news\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.scmetal.cz\/en\/news\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.scmetal.cz\/en\/news\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Dom\u016f","item":"https:\/\/www.scmetal.cz\/?lang=en"},{"@type":"ListItem","position":2,"name":"News"}]},{"@type":"WebSite","@id":"https:\/\/www.scmetal.cz\/#website","url":"https:\/\/www.scmetal.cz\/","name":"scmetal.cz","description":"komplexn\u00ed servis pro stroj\u00edrenstv\u00ed","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.scmetal.cz\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/www.scmetal.cz\/en\/wp-json\/wp\/v2\/pages\/9030","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.scmetal.cz\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.scmetal.cz\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.scmetal.cz\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.scmetal.cz\/en\/wp-json\/wp\/v2\/comments?post=9030"}],"version-history":[{"count":3,"href":"https:\/\/www.scmetal.cz\/en\/wp-json\/wp\/v2\/pages\/9030\/revisions"}],"predecessor-version":[{"id":10527,"href":"https:\/\/www.scmetal.cz\/en\/wp-json\/wp\/v2\/pages\/9030\/revisions\/10527"}],"wp:attachment":[{"href":"https:\/\/www.scmetal.cz\/en\/wp-json\/wp\/v2\/media?parent=9030"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}